{"id":11337,"date":"2026-05-07T16:20:05","date_gmt":"2026-05-07T14:20:05","guid":{"rendered":"https:\/\/mucbo.org\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/"},"modified":"2026-05-07T16:23:24","modified_gmt":"2026-05-07T14:23:24","slug":"el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus","status":"publish","type":"post","link":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/","title":{"rendered":"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos"},"content":{"rendered":"<p>El MUCBO celebra un a\u00f1o m\u00e1s el D\u00eda Internacional de los Museos, que se celebrar\u00e1 el pr\u00f3ximo lunes 18 de mayo con una programaci\u00f3n especial incluida dentro de esta iniciativa impulsada por el <a href=\"https:\/\/icom.museum\/en\/international-museum-day-2\/\">ICOM<\/a> y establecida en la red de museos de nuestra isla de la mano del <a href=\"https:\/\/www.conselldemallorca.es\/agenda\">Consell de Mallorca.<\/a><\/p><p>En el contexto de estas celebraciones, el MUCBO ha programado para el d\u00eda 14 de mayo una conferencia muy especial titulada <strong>\u00ab<a href=\"https:\/\/mucbo.org\/conferencia-de-francesc-gasco\/\">Descubriendo la biolog\u00eda de <em>Spinosaurus mirabilis<\/em><\/a>\u00bb<\/strong>, que ser\u00e1 impartida por el paleont\u00f3logo y divulgador cient\u00edfico Francesc Gasc\u00f3.<\/p><p>El lema de la jornada de este a\u00f1o es <strong>\u00abMuseos uniendo un mundo dividido\u00bb<\/strong>, con la voluntad de poner el acento en el papel de los museos como espacios capaces de conectar realidades diversas y superar fracturas culturales, sociales y geopol\u00edticas, promoviendo el di\u00e1logo, la comprensi\u00f3n, la inclusi\u00f3n y la convivencia pac\u00edfica tanto dentro de las comunidades como entre pueblos de todo el mundo. Adem\u00e1s, en 2026 se incluyen tambi\u00e9n las celebraciones del 80.\u00ba aniversario del ICOM, una conmemoraci\u00f3n que subraya una trayectoria de ocho d\u00e9cadas de compromiso con el apoyo a los museos y con su funci\u00f3n transformadora dentro de la sociedad.<\/p><p>El objetivo del D\u00eda Internacional de los Museos es concienciar sobre el hecho de que \u00ablos museos son un medio importante de intercambio cultural, de enriquecimiento de las culturas y de desarrollo de la comprensi\u00f3n mutua, la cooperaci\u00f3n y la paz entre los pueblos\u00bb. Organizado el 18 de mayo de cada a\u00f1o o en torno a esta fecha, los eventos y actividades programados para celebrar el D\u00eda Internacional de los Museos pueden durar un d\u00eda, un fin de semana o toda una semana. El DIM se celebr\u00f3 por primera vez hace 40 a\u00f1os. En todo el mundo, cada vez m\u00e1s museos participan en el D\u00eda Internacional de los Museos. El a\u00f1o pasado, m\u00e1s de 37.000 museos participaron en el evento en alrededor de 158 pa\u00edses y territorios.<\/p><p><\/p><figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1920\" height=\"346\" src=\"https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_.png\" alt=\"\" class=\"wp-image-11221\" style=\"aspect-ratio:5.54996776273372;width:192px;height:auto\" srcset=\"https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_.png 1920w, https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_-768x138.png 768w, https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_-1536x277.png 1536w, https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_-600x108.png 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1850\" height=\"770\" src=\"https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1.png\" alt=\"\" class=\"wp-image-11218\" style=\"aspect-ratio:2.40268156424581;width:171px;height:auto\" srcset=\"https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1.png 1850w, https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1-768x320.png 768w, https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1-1536x639.png 1536w, https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1-600x250.png 600w\" sizes=\"(max-width: 1850px) 100vw, 1850px\" \/><\/figure><figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1200\" height=\"625\" src=\"https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1.jpg\" alt=\"\" class=\"wp-image-11249\" style=\"aspect-ratio:1.9201381394344916;width:183px;height:auto\" srcset=\"https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1.jpg 1200w, https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1-768x400.jpg 768w, https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1-600x313.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>El MUCBO celebra un a\u00f1o m\u00e1s el D\u00eda Internacional de los Museos, que se celebrar\u00e1 el pr\u00f3ximo lunes 18 de mayo con una programaci\u00f3n especial incluida dentro de esta iniciativa impulsada por el ICOM y establecida en la red de museos de nuestra isla de la mano del Consell de Mallorca. En el contexto de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[136],"tags":[],"class_list":["post-11337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El MUCBO se suma a las celebraciones del Dia Internacional de los Museos - MUCBO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos - MUCBO\" \/>\n<meta property=\"og:description\" content=\"El MUCBO celebra un a\u00f1o m\u00e1s el D\u00eda Internacional de los Museos, que se celebrar\u00e1 el pr\u00f3ximo lunes 18 de mayo con una programaci\u00f3n especial incluida dentro de esta iniciativa impulsada por el ICOM y establecida en la red de museos de nuestra isla de la mano del Consell de Mallorca. En el contexto de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/\" \/>\n<meta property=\"og:site_name\" content=\"MUCBO\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T14:20:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T14:23:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png\" \/>\n\t<meta property=\"og:image:width\" content=\"537\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mpcloquell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mpcloquell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/\",\"url\":\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/\",\"name\":\"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos - MUCBO\",\"isPartOf\":{\"@id\":\"https:\/\/mucbo.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png\",\"datePublished\":\"2026-05-07T14:20:05+00:00\",\"dateModified\":\"2026-05-07T14:23:24+00:00\",\"author\":{\"@id\":\"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#primaryimage\",\"url\":\"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png\",\"contentUrl\":\"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png\",\"width\":537,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/mucbo.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mucbo.org\/es\/#website\",\"url\":\"https:\/\/mucbo.org\/es\/\",\"name\":\"MUCBO\",\"description\":\"Fundaci\u00f3 Jard\u00ed Bot\u00e0nic de S\u00f3ller - Museu Balear de Ci\u00e8ncies Naturals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mucbo.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1\",\"name\":\"mpcloquell\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos - MUCBO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/","og_locale":"es_ES","og_type":"article","og_title":"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos - MUCBO","og_description":"El MUCBO celebra un a\u00f1o m\u00e1s el D\u00eda Internacional de los Museos, que se celebrar\u00e1 el pr\u00f3ximo lunes 18 de mayo con una programaci\u00f3n especial incluida dentro de esta iniciativa impulsada por el ICOM y establecida en la red de museos de nuestra isla de la mano del Consell de Mallorca. En el contexto de [&hellip;]","og_url":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/","og_site_name":"MUCBO","article_published_time":"2026-05-07T14:20:05+00:00","article_modified_time":"2026-05-07T14:23:24+00:00","og_image":[{"width":537,"height":767,"url":"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png","type":"image\/png"}],"author":"mpcloquell","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mpcloquell","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/","url":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/","name":"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos - MUCBO","isPartOf":{"@id":"https:\/\/mucbo.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#primaryimage"},"image":{"@id":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#primaryimage"},"thumbnailUrl":"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png","datePublished":"2026-05-07T14:20:05+00:00","dateModified":"2026-05-07T14:23:24+00:00","author":{"@id":"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1"},"breadcrumb":{"@id":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#primaryimage","url":"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png","contentUrl":"https:\/\/mucbo.org\/wp-content\/uploads\/Captura-de-pantalla-2026-05-07-160831.png","width":537,"height":767},{"@type":"BreadcrumbList","@id":"https:\/\/mucbo.org\/es\/el-mucbo-se-suma-a-les-celebracions-del-dia-internacional-dels-museus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/mucbo.org\/es\/"},{"@type":"ListItem","position":2,"name":"El MUCBO se suma a las celebraciones del Dia Internacional de los Museos"}]},{"@type":"WebSite","@id":"https:\/\/mucbo.org\/es\/#website","url":"https:\/\/mucbo.org\/es\/","name":"MUCBO","description":"Fundaci\u00f3 Jard\u00ed Bot\u00e0nic de S\u00f3ller - Museu Balear de Ci\u00e8ncies Naturals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mucbo.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1","name":"mpcloquell"}]}},"_links":{"self":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts\/11337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/comments?post=11337"}],"version-history":[{"count":3,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts\/11337\/revisions"}],"predecessor-version":[{"id":11344,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts\/11337\/revisions\/11344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/media\/11334"}],"wp:attachment":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/media?parent=11337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/categories?post=11337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/tags?post=11337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}