{"id":11226,"date":"2026-05-06T15:07:13","date_gmt":"2026-05-06T13:07:13","guid":{"rendered":"https:\/\/mucbo.org\/conferencia-de-francesc-gasco\/"},"modified":"2026-05-07T14:51:44","modified_gmt":"2026-05-07T12:51:44","slug":"conferencia-de-francesc-gasco","status":"publish","type":"post","link":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/","title":{"rendered":"Descubriendo la biologia de Spinosaurus mirabilis"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En el marco del D\u00eda Internacional de los Museos 2026, el paleont\u00f3logo y divulgador cient\u00edfico Francesc Gasc\u00f3-Lluna (El Pakozoico) ofrece esta conferencia sobre los \u00faltimos descubrimientos publicados a ra\u00edz de las excavaciones que se llevaron a cabo en N\u00edger en el oto\u00f1o de 2022, junto a un equipo de paleont\u00f3logos liderado por la Universidad de Chicago, que cont\u00f3 con la participaci\u00f3n de ocho paleont\u00f3logos espa\u00f1oles. De aquel trabajo de campo ha surgido recientemente la descripci\u00f3n de una nueva especie para la ciencia: <em>Spinosaurus mirabilis<\/em>.<\/p><p class=\"wp-block-paragraph\">En esta charla seguiremos los pasos de la expedici\u00f3n, desde la vida y el trabajo en las duras condiciones del desierto hasta el estudio de los f\u00f3siles en el laboratorio y la reconstrucci\u00f3n de la biolog\u00eda de este animal. Un recorrido por el proceso de investigaci\u00f3n que hay detr\u00e1s del descubrimiento, estudio y descripci\u00f3n de una nueva especie f\u00f3sil, acompa\u00f1ado de an\u00e9cdotas de campo, contexto geol\u00f3gico y las dificultades y particularidades de trabajar en uno de los grandes desiertos del planeta.<\/p><p class=\"wp-block-paragraph\"><\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"1886\" height=\"1260\" src=\"https:\/\/mucbo.org\/wp-content\/uploads\/BrookeSweeney_Dino_Leg2_2022_1-82.jpg\" alt=\"\" class=\"wp-image-11241\" style=\"aspect-ratio:1.3272107835876166;width:410px;height:auto\" srcset=\"https:\/\/mucbo.org\/wp-content\/uploads\/BrookeSweeney_Dino_Leg2_2022_1-82.jpg 1886w, https:\/\/mucbo.org\/wp-content\/uploads\/BrookeSweeney_Dino_Leg2_2022_1-82-768x513.jpg 768w, https:\/\/mucbo.org\/wp-content\/uploads\/BrookeSweeney_Dino_Leg2_2022_1-82-1536x1026.jpg 1536w, https:\/\/mucbo.org\/wp-content\/uploads\/BrookeSweeney_Dino_Leg2_2022_1-82-600x401.jpg 600w\" sizes=\"(max-width: 1886px) 100vw, 1886px\" \/><\/figure><\/div><p class=\"wp-block-paragraph\"><strong>14 de mayo a las 18 h en el MUCBO.<\/strong><\/p><p class=\"wp-block-paragraph\"><\/p><p class=\"wp-block-paragraph\"><\/p><figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1920\" height=\"346\" src=\"https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_.png\" alt=\"\" class=\"wp-image-11221\" style=\"aspect-ratio:5.549705791266646;width:309px;height:auto\" srcset=\"https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_.png 1920w, https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_-768x138.png 768w, https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_-1536x277.png 1536w, https:\/\/mucbo.org\/wp-content\/uploads\/ICOM_Logo.svg_-600x108.png 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure><figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1850\" height=\"770\" src=\"https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1.png\" alt=\"\" class=\"wp-image-11218\" style=\"aspect-ratio:2.40268156424581;width:303px;height:auto\" srcset=\"https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1.png 1850w, https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1-768x320.png 768w, https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1-1536x639.png 1536w, https:\/\/mucbo.org\/wp-content\/uploads\/Logo-CIM-dreta-color-1-600x250.png 600w\" sizes=\"(max-width: 1850px) 100vw, 1850px\" \/><\/figure><figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1200\" height=\"625\" src=\"https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1.jpg\" alt=\"\" class=\"wp-image-11250\" style=\"width:323px;height:auto\" srcset=\"https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1.jpg 1200w, https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1-768x400.jpg 768w, https:\/\/mucbo.org\/wp-content\/uploads\/Carrousel-xarxa-museus-1200x625-1-600x313.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda Internacional de los Museos 2026, el paleont\u00f3logo y divulgador cient\u00edfico Francesc Gasc\u00f3-Lluna (El Pakozoico) ofrece esta conferencia sobre los \u00faltimos descubrimientos publicados a ra\u00edz de las excavaciones que se llevaron a cabo en N\u00edger en el oto\u00f1o de 2022, junto a un equipo de paleont\u00f3logos liderado por la Universidad de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[134,132],"tags":[],"class_list":["post-11226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-pasadas","category-agenda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Descubriendo la biologia de Spinosaurus mirabilis - MUCBO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubriendo la biologia de Spinosaurus mirabilis - MUCBO\" \/>\n<meta property=\"og:description\" content=\"En el marco del D\u00eda Internacional de los Museos 2026, el paleont\u00f3logo y divulgador cient\u00edfico Francesc Gasc\u00f3-Lluna (El Pakozoico) ofrece esta conferencia sobre los \u00faltimos descubrimientos publicados a ra\u00edz de las excavaciones que se llevaron a cabo en N\u00edger en el oto\u00f1o de 2022, junto a un equipo de paleont\u00f3logos liderado por la Universidad de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/\" \/>\n<meta property=\"og:site_name\" content=\"MUCBO\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-06T13:07:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T12:51:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mpcloquell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mpcloquell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/\",\"url\":\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/\",\"name\":\"Descubriendo la biologia de Spinosaurus mirabilis - MUCBO\",\"isPartOf\":{\"@id\":\"https:\/\/mucbo.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg\",\"datePublished\":\"2026-05-06T13:07:13+00:00\",\"dateModified\":\"2026-05-07T12:51:44+00:00\",\"author\":{\"@id\":\"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1\"},\"breadcrumb\":{\"@id\":\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#primaryimage\",\"url\":\"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg\",\"contentUrl\":\"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/mucbo.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubriendo la biologia de Spinosaurus mirabilis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mucbo.org\/es\/#website\",\"url\":\"https:\/\/mucbo.org\/es\/\",\"name\":\"MUCBO\",\"description\":\"Fundaci\u00f3 Jard\u00ed Bot\u00e0nic de S\u00f3ller - Museu Balear de Ci\u00e8ncies Naturals\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mucbo.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1\",\"name\":\"mpcloquell\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubriendo la biologia de Spinosaurus mirabilis - MUCBO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/","og_locale":"es_ES","og_type":"article","og_title":"Descubriendo la biologia de Spinosaurus mirabilis - MUCBO","og_description":"En el marco del D\u00eda Internacional de los Museos 2026, el paleont\u00f3logo y divulgador cient\u00edfico Francesc Gasc\u00f3-Lluna (El Pakozoico) ofrece esta conferencia sobre los \u00faltimos descubrimientos publicados a ra\u00edz de las excavaciones que se llevaron a cabo en N\u00edger en el oto\u00f1o de 2022, junto a un equipo de paleont\u00f3logos liderado por la Universidad de [&hellip;]","og_url":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/","og_site_name":"MUCBO","article_published_time":"2026-05-06T13:07:13+00:00","article_modified_time":"2026-05-07T12:51:44+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg","type":"image\/jpeg"}],"author":"mpcloquell","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mpcloquell","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/","url":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/","name":"Descubriendo la biologia de Spinosaurus mirabilis - MUCBO","isPartOf":{"@id":"https:\/\/mucbo.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#primaryimage"},"image":{"@id":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#primaryimage"},"thumbnailUrl":"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg","datePublished":"2026-05-06T13:07:13+00:00","dateModified":"2026-05-07T12:51:44+00:00","author":{"@id":"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1"},"breadcrumb":{"@id":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#primaryimage","url":"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg","contentUrl":"https:\/\/mucbo.org\/wp-content\/uploads\/2026-Conferencies-xerrades-i-presentacions-de-llibres-MUCBO-2.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/mucbo.org\/es\/conferencia-de-francesc-gasco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/mucbo.org\/es\/"},{"@type":"ListItem","position":2,"name":"Descubriendo la biologia de Spinosaurus mirabilis"}]},{"@type":"WebSite","@id":"https:\/\/mucbo.org\/es\/#website","url":"https:\/\/mucbo.org\/es\/","name":"MUCBO","description":"Fundaci\u00f3 Jard\u00ed Bot\u00e0nic de S\u00f3ller - Museu Balear de Ci\u00e8ncies Naturals","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mucbo.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mucbo.org\/es\/#\/schema\/person\/af988b76257e083c4560ef156b2e2cb1","name":"mpcloquell"}]}},"_links":{"self":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts\/11226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/comments?post=11226"}],"version-history":[{"count":5,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts\/11226\/revisions"}],"predecessor-version":[{"id":11257,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/posts\/11226\/revisions\/11257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/media\/11245"}],"wp:attachment":[{"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/media?parent=11226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/categories?post=11226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mucbo.org\/es\/wp-json\/wp\/v2\/tags?post=11226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}